{"id":209,"date":"2023-09-17T17:46:29","date_gmt":"2023-09-17T08:46:29","guid":{"rendered":"https:\/\/edo-business.jp\/?page_id=209"},"modified":"2023-09-18T10:29:01","modified_gmt":"2023-09-18T01:29:01","slug":"contact","status":"publish","type":"page","link":"https:\/\/www.edo-business.jp\/vi\/contact\/","title":{"rendered":"Li\u00ean h\u1ec7"},"content":{"rendered":"\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f111-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/vi\/wp-json\/wp\/v2\/pages\/209#wpcf7-f111-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"111\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.9.4\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f111-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<p><label> T\u00ean<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nguy\u1ec5n V\u0103n An\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/label>\n<\/p>\n<p><label> Email<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"nguyen_van_an@example.com\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> Lo\u1ea1i li\u00ean h\u1ec7<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-subject\"><option value=\"\">&#8212;Please choose an option&#8212;<\/option><option value=\"B\u00e1o gi\u00e1\">B\u00e1o gi\u00e1<\/option><option value=\"T\u01b0 v\u1ea5n\">T\u01b0 v\u1ea5n<\/option><option value=\"\u0110\u1eb7t h\u00e0ng\">\u0110\u1eb7t h\u00e0ng<\/option><\/select><\/span> <\/label>\n<\/p>\n<p><label> N\u1ed9i dung<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nh\u1eadp n\u1ed9i dung chi ti\u1ebft\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"G\u1eedi\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_locale":"vi","_original_post":"https:\/\/edo-business.jp\/?page_id=7","vkexunit_cta_each_option":"","footnotes":""},"class_list":["post-209","page","type-page","status-publish","has-post-thumbnail","hentry","vi"],"_links":{"self":[{"href":"https:\/\/www.edo-business.jp\/wp-json\/wp\/v2\/pages\/209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.edo-business.jp\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.edo-business.jp\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.edo-business.jp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.edo-business.jp\/wp-json\/wp\/v2\/comments?post=209"}],"version-history":[{"count":2,"href":"https:\/\/www.edo-business.jp\/wp-json\/wp\/v2\/pages\/209\/revisions"}],"predecessor-version":[{"id":214,"href":"https:\/\/www.edo-business.jp\/wp-json\/wp\/v2\/pages\/209\/revisions\/214"}],"wp:attachment":[{"href":"https:\/\/www.edo-business.jp\/wp-json\/wp\/v2\/media?parent=209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}